{"id":21324,"date":"2022-02-17T18:02:25","date_gmt":"2022-02-17T17:02:25","guid":{"rendered":"https:\/\/puente-colgante.com\/?p=21324"},"modified":"2022-02-17T18:02:25","modified_gmt":"2022-02-17T17:02:25","slug":"mes-de-los-museos-de-la-costa-vasca","status":"publish","type":"post","link":"https:\/\/puente-colgante.com\/eu\/mes-de-los-museos-de-la-costa-vasca\/","title":{"rendered":"Mes de los Museos de la costa vasca"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<h1>Mes de los Museos de la costa vasca<\/h1>\n<p>[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1645117387909{padding-top: 5% !important;}&#8221;]Este Marzo es el mes de los museos de la costa vasca, ven a conocer todo lo que rodea nuestras costas. Te esperamos.[\/vc_column_text][dfd_button button_text=&#8221;M\u00e1s Informaci\u00f3n&#8221; buttom_link_src=&#8221;url:https%3A%2F%2Fpuente-colgante.com%2Fwp-content%2Fuploads%2F2022%2F02%2FMES-MUSEOS-COSTA-VASCA-EUS-CAS-1.pdf|||&#8221; style=&#8221;style_2&#8243; box_shadow=&#8221;horizontal:px|vertical:px|blur:px|spread:px|style:none|&#8221; hover_box_shadow=&#8221;horizontal:px|vertical:px|blur:px|spread:px|style:none|&#8221;][dfd_button button_text=&#8221;Ver programa&#8221; buttom_link_src=&#8221;url:https%3A%2F%2Fpuente-colgante.com%2Fwp-content%2Fuploads%2F2022%2F02%2Fprograma_Mes_Museos_2022_online-002.pdf|||&#8221; style=&#8221;style_2&#8243; box_shadow=&#8221;horizontal:px|vertical:px|blur:px|spread:px|style:none|&#8221; hover_box_shadow=&#8221;horizontal:px|vertical:px|blur:px|spread:px|style:none|&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;21332&#8243; img_size=&#8221;Large&#8221; css=&#8221;.vc_custom_1645117340399{padding-bottom: 5% !important;}&#8221;][vc_single_image image=&#8221;21338&#8243; img_size=&#8221;large&#8221;][vc_single_image image=&#8221;21335&#8243; img_size=&#8221;large&#8221;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Mes de los Museos de la costa vasca [\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1645117387909{padding-top: 5% !important;}&#8221;]Este Marzo es el mes de los museos de la costa vasca, ven a conocer todo lo que rodea nuestras costas. Te esperamos.[\/vc_column_text][dfd_button button_text=&#8221;M\u00e1s Informaci\u00f3n&#8221; buttom_link_src=&#8221;url:https%3A%2F%2Fpuente-colgante.com%2Fwp-content%2Fuploads%2F2022%2F02%2FMES-MUSEOS-COSTA-VASCA-EUS-CAS-1.pdf|||&#8221; style=&#8221;style_2&#8243; box_shadow=&#8221;horizontal:px|vertical:px|blur:px|spread:px|style:none|&#8221; hover_box_shadow=&#8221;horizontal:px|vertical:px|blur:px|spread:px|style:none|&#8221;][dfd_button button_text=&#8221;Ver programa&#8221; buttom_link_src=&#8221;url:https%3A%2F%2Fpuente-colgante.com%2Fwp-content%2Fuploads%2F2022%2F02%2Fprograma_Mes_Museos_2022_online-002.pdf|||&#8221; style=&#8221;style_2&#8243; box_shadow=&#8221;horizontal:px|vertical:px|blur:px|spread:px|style:none|&#8221; hover_box_shadow=&#8221;horizontal:px|vertical:px|blur:px|spread:px|style:none|&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;21332&#8243; img_size=&#8221;Large&#8221; css=&#8221;.vc_custom_1645117340399{padding-bottom: 5% !important;}&#8221;][vc_single_image image=&#8221;21338&#8243; img_size=&#8221;large&#8221;][vc_single_image image=&#8221;21335&#8243; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21332,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[],"class_list":["post-21324","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","grve-entry-item","grve-blog-item"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mes de los Museos de la costa vasca - Puente Colgante<\/title>\n<meta name=\"description\" content=\"Mes de los Museos de la costa vasca Este Marzo es el mes de los museos de la costa vasca, ven a conocer todo lo que rodea nuestras costas. Te esperamos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/\" \/>\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mes de los Museos de la costa vasca - Puente Colgante\" \/>\n<meta property=\"og:description\" content=\"Mes de los Museos de la costa vasca Este Marzo es el mes de los museos de la costa vasca, ven a conocer todo lo que rodea nuestras costas. Te esperamos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/\" \/>\n<meta property=\"og:site_name\" content=\"Puente Colgante\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-17T17:02:25+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/puente-colgante.com\/wp-content\/uploads\/2022\/02\/MUSEOS_COSTA_VASCA_2.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/person\/1cb7a33dae376b9d2c073110e8ec4b9b\"},\"headline\":\"Mes de los Museos de la costa vasca\",\"datePublished\":\"2022-02-17T17:02:25+00:00\",\"dateModified\":\"2022-02-17T17:02:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/\"},\"wordCount\":199,\"publisher\":{\"@id\":\"https:\/\/puente-colgante.com\/#organization\"},\"articleSection\":[\"Noticias\"],\"inLanguage\":\"eu-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/\",\"url\":\"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/\",\"name\":\"Mes de los Museos de la costa vasca - Puente Colgante\",\"isPartOf\":{\"@id\":\"https:\/\/puente-colgante.com\/#website\"},\"datePublished\":\"2022-02-17T17:02:25+00:00\",\"dateModified\":\"2022-02-17T17:02:25+00:00\",\"description\":\"Mes de los Museos de la costa vasca Este Marzo es el mes de los museos de la costa vasca, ven a conocer todo lo que rodea nuestras costas. Te esperamos.\",\"breadcrumb\":{\"@id\":\"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/puente-colgante.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mes de los Museos de la costa vasca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/puente-colgante.com\/#website\",\"url\":\"https:\/\/puente-colgante.com\/\",\"name\":\"Puente Colgante\",\"description\":\"Web Oficial del Puente Colgante | Puente Bizkaia\",\"publisher\":{\"@id\":\"https:\/\/puente-colgante.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/puente-colgante.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/puente-colgante.com\/#organization\",\"name\":\"Puente Colgante\",\"url\":\"https:\/\/puente-colgante.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png\",\"contentUrl\":\"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png\",\"width\":742,\"height\":560,\"caption\":\"Puente Colgante\"},\"image\":{\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/person\/1cb7a33dae376b9d2c073110e8ec4b9b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fd07c919907115af214a1e73130252784e8d50e757c8cd800e69acdfe5f2ff28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fd07c919907115af214a1e73130252784e8d50e757c8cd800e69acdfe5f2ff28?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/puente-colgante.com\"],\"url\":\"https:\/\/puente-colgante.com\/eu\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mes de los Museos de la costa vasca - Puente Colgante","description":"Mes de los Museos de la costa vasca Este Marzo es el mes de los museos de la costa vasca, ven a conocer todo lo que rodea nuestras costas. Te esperamos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/","og_locale":"eu_ES","og_type":"article","og_title":"Mes de los Museos de la costa vasca - Puente Colgante","og_description":"Mes de los Museos de la costa vasca Este Marzo es el mes de los museos de la costa vasca, ven a conocer todo lo que rodea nuestras costas. Te esperamos.","og_url":"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/","og_site_name":"Puente Colgante","article_published_time":"2022-02-17T17:02:25+00:00","author":"admin","twitter_card":"summary_large_image","twitter_image":"https:\/\/puente-colgante.com\/wp-content\/uploads\/2022\/02\/MUSEOS_COSTA_VASCA_2.jpg","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/#article","isPartOf":{"@id":"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/"},"author":{"name":"admin","@id":"https:\/\/puente-colgante.com\/#\/schema\/person\/1cb7a33dae376b9d2c073110e8ec4b9b"},"headline":"Mes de los Museos de la costa vasca","datePublished":"2022-02-17T17:02:25+00:00","dateModified":"2022-02-17T17:02:25+00:00","mainEntityOfPage":{"@id":"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/"},"wordCount":199,"publisher":{"@id":"https:\/\/puente-colgante.com\/#organization"},"articleSection":["Noticias"],"inLanguage":"eu-ES"},{"@type":"WebPage","@id":"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/","url":"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/","name":"Mes de los Museos de la costa vasca - Puente Colgante","isPartOf":{"@id":"https:\/\/puente-colgante.com\/#website"},"datePublished":"2022-02-17T17:02:25+00:00","dateModified":"2022-02-17T17:02:25+00:00","description":"Mes de los Museos de la costa vasca Este Marzo es el mes de los museos de la costa vasca, ven a conocer todo lo que rodea nuestras costas. Te esperamos.","breadcrumb":{"@id":"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/puente-colgante.com\/mes-de-los-museos-de-la-costa-vasca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/puente-colgante.com\/en\/"},{"@type":"ListItem","position":2,"name":"Mes de los Museos de la costa vasca"}]},{"@type":"WebSite","@id":"https:\/\/puente-colgante.com\/#website","url":"https:\/\/puente-colgante.com\/","name":"Puente Colgante","description":"Web Oficial del Puente Colgante | Puente Bizkaia","publisher":{"@id":"https:\/\/puente-colgante.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/puente-colgante.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/puente-colgante.com\/#organization","name":"Puente Colgante","url":"https:\/\/puente-colgante.com\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/","url":"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png","contentUrl":"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png","width":742,"height":560,"caption":"Puente Colgante"},"image":{"@id":"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/puente-colgante.com\/#\/schema\/person\/1cb7a33dae376b9d2c073110e8ec4b9b","name":"admin","image":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/puente-colgante.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fd07c919907115af214a1e73130252784e8d50e757c8cd800e69acdfe5f2ff28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fd07c919907115af214a1e73130252784e8d50e757c8cd800e69acdfe5f2ff28?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/puente-colgante.com"],"url":"https:\/\/puente-colgante.com\/eu\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/puente-colgante.com\/eu\/wp-json\/wp\/v2\/posts\/21324","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puente-colgante.com\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puente-colgante.com\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puente-colgante.com\/eu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/puente-colgante.com\/eu\/wp-json\/wp\/v2\/comments?post=21324"}],"version-history":[{"count":0,"href":"https:\/\/puente-colgante.com\/eu\/wp-json\/wp\/v2\/posts\/21324\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puente-colgante.com\/eu\/wp-json\/wp\/v2\/media\/21332"}],"wp:attachment":[{"href":"https:\/\/puente-colgante.com\/eu\/wp-json\/wp\/v2\/media?parent=21324"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puente-colgante.com\/eu\/wp-json\/wp\/v2\/categories?post=21324"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puente-colgante.com\/eu\/wp-json\/wp\/v2\/tags?post=21324"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}