{"id":31292,"date":"2019-05-03T12:44:08","date_gmt":"2019-05-03T10:44:08","guid":{"rendered":"https:\/\/puente-colgante.com\/dia-internacional-de-los-museos\/"},"modified":"2019-05-03T12:44:08","modified_gmt":"2019-05-03T10:44:08","slug":"dia-internacional-de-los-museos","status":"publish","type":"post","link":"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/","title":{"rendered":"D\u00eda Internacional de los Museos"},"content":{"rendered":"<p>Os informamos de las actividades organizadas en los museos con motivo del D\u00eda Internacional de los museos.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><strong>Los museos como ejes culturales: el futuro de las tradiciones.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>BILBAO<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Arkeologi Museoa<\/strong><br \/>\n94 404 09 90<\/p>\n<p>18 de mayo.<\/p>\n<p>Jornada de puertas abiertas: entrada y actividades gratuitas.<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>11:30 Taller familiar: Arkeologoa egun batez. Biling\u00fce.<\/p>\n<p>13:15 Visita comentada: El museo pieza a pieza- El brazalete de arquero de Kobeaga (Ispaster). Euskaraz.<\/p>\n<p>17:00 Visita guiada 1: Rompiendo mitos.<\/p>\n<p>18:15 Visita guiada 2: Arte en la Prehistoria.<\/p>\n<p>&nbsp;<\/p>\n<p>19 de mayo.<\/p>\n<p>11:30 Taller familiar: Caminando entre las bestias. Biling\u00fce.<\/p>\n<p>13:15 Visita comentada: El museo pieza a pieza- El brazalete de arquero de Kobeaga (Ispaster). Castellano.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Athletic Club Museoa<\/strong><br \/>\n94 466 11 00<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada al museo y visita guiada a San Mam\u00e9s gratuita.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Museo de Bellas Artes de Bilbao<\/strong><br \/>\n94 439 60 60<\/p>\n<p>18 y 19 de mayo.<\/p>\n<p>Entrada y audiogu\u00eda gratuitas (bajo disponibilidad).<\/p>\n<p>Colecci\u00f3n permanente y exposici\u00f3n temporal \u201cABC. El alfabeto del Museo de Bilbao\u201d.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h1>Museo Reproducciones Bilbao<\/h1>\n<p>94 415 02 31<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Museo Mar\u00edtimo R\u00eda de Bilbao<\/strong><\/p>\n<p>94 608 55 00<\/p>\n<p>&nbsp;<\/p>\n<p>16 de mayo.<\/p>\n<p>12:00 Instalaci\u00f3n obra ganadora del Concurso de Instalaciones Art\u00edsticas en Contenedores en el exterior.<\/p>\n<p>&nbsp;<\/p>\n<p>19:00 Conferencia \u201cQuint\u00edn de Torre, tradici\u00f3n y modernidad\u201d a cargo de Miriam Alzurri, t\u00e9cnica de Exposiciones del Museo de Bellas Artes de Bilbao y experta en la figura de este escultor bilba\u00edno. Gratuita. Acceso libre hasta completar aforo.<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita al museo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Museo de\u00a0Arte Sacro<\/strong><br \/>\n94 432 01 25<br \/>\n18 y 19 de mayo.<\/p>\n<p>Entrada gratuita a la colecci\u00f3n permanente.<\/p>\n<p>Sala de escape \u201cLa abad\u00eda de Atxuri\u201d. 50% de descuento. Grupos de 3-6 personas. Reserva previa: 94 432 01 25.<\/p>\n<p>&nbsp;<\/p>\n<h1>Museo Vasco<\/h1>\n<h1>94 415 02 31<\/h1>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h1>Museo del Nacionalismo Vasco<\/h1>\n<p>94 405 64 50<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Guggenheim Bilbao Museoa<\/strong><\/p>\n<p>94 435 90 80<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita.<\/p>\n<p>Visitas guiadas: 12:30h (general) y 17:00h (express). Aforo limitado.<\/p>\n<p>Los visitantes podr\u00e1n compartir sus buenos deseos participando en el \u201c\u00c1rbol de los deseos\u201d de Yoko Ono.\u00a0 Consultar horario en informaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Museo de Pasos de Semana Santa<\/strong><\/p>\n<p>94 415 04 33<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Museo Taurino de Bilbao<\/strong><\/p>\n<p>94 444 86 98<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Euskeraren Etxea<\/strong><\/p>\n<p>94 402 80 81<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita.<\/p>\n<p>&nbsp;<\/p>\n<p>ABANTO-ZIERBENA (GALLARTA)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Museo de la Miner\u00eda del Pa\u00eds Vasco<\/strong><\/p>\n<p>94 636 36 82<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>BAKIO<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Txakolingunea<\/strong><\/p>\n<p>94 602 85 13<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p>BALMASEDA<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>La Encartada Fabrika-Museoa<\/strong><\/p>\n<p>94 680 07 78<\/p>\n<p>&nbsp;<\/p>\n<p>18 y 19 de mayo.<\/p>\n<p>Visitas guiadas gratuitas a las horas en punto.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>C.I. Pasi\u00f3n Viviente de Balmaseda<\/strong><\/p>\n<p>94 680 14 38<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Visitas guiadas gratuitas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Museo de la Historia de la Villa<\/strong><\/p>\n<p>657 795 806<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita.<\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p>BERANGO<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Museo Memorial del Cintur\u00f3n de Hierro<\/strong><\/p>\n<p>94 668 21 43<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita al museo y visitas guiadas de manera personalizada. 17:00-20:00.<\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p>BERRIZ<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Museo Margarita Mar\u00eda de Berriz al Mundo<\/strong><\/p>\n<p>94 622 55 30<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita.<\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p>BERMEO<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Arrantzaleen Museoa <\/strong><\/p>\n<p>94 688 11 71<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita y regalo para las personas que visiten el museo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p>DURANGO<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Arte eta Historia Museoa<\/strong><\/p>\n<p>94 603 00 20<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>19:00 Bertso-saio plastiko esperimentala. Igor Elortza eta Miren Amuriza bertsolariek Maite Berriozabal gai-jartzailearekin batera arte plastikoak eta ahozko tradizioa ustartuko dituzte.<\/p>\n<p>&nbsp;<\/p>\n<p>ELORRIO<\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p><strong>Museo San Valentin de Berrio-Otxoa<\/strong><\/p>\n<p>94 682 04 55<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita.<\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p>GALDAMES<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Torre Loizaga. Museo de coches antiguos y cl\u00e1sicos<\/strong><\/p>\n<p>94 680 13 56<\/p>\n<p>&nbsp;<\/p>\n<p>\u00bf\u00bf??<\/p>\n<p>&nbsp;<\/p>\n<p>GERNIKA-LUMO<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Museo Euskal Herria <\/strong><\/p>\n<p>94 625 54 51<\/p>\n<p>17 de mayo<\/p>\n<p>18:00 Paseo por el jard\u00edn del museo y el Parque Europa. Visita guiada gratuita. Plazas limitadas. Necesaria reserva previa.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita al museo y obsequio.<\/p>\n<p>Diversas actividades en torno a la Anchoa: talleres familiares, conferencia y degustaci\u00f3n de pintxos.<\/p>\n<p>&nbsp;<\/p>\n<p>16:30-23:00 Noche de los museos. Apertura extraordinaria. Entrada gratuita al museo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p><strong>Fundaci\u00f3n Museo de la Paz de Gernika<\/strong><\/p>\n<p>94 627 02 13<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada y actividades gratuitas.<\/p>\n<p>&nbsp;<\/p>\n<p>11:30 Conferencia a cargo de Roberto Fuertes Garc\u00eda \u201cPatrimonio y memoria en Chile: el ejemplo de Villa Grimaldi\u201d.<\/p>\n<p>12:45 Ruta guiada Memoritour Gernika: \u201cLa reconstrucci\u00f3n de Gernika\u201d.<\/p>\n<p>13:00 Visita guiada a la exposici\u00f3n permanente del museo.<\/p>\n<p>&nbsp;<\/p>\n<p>19 de mayo.<\/p>\n<p>Entrada y actividades gratuitas.<\/p>\n<p>&nbsp;<\/p>\n<p>11:30 Taller familiar<\/p>\n<p>12:30 Visita guiada a la exposici\u00f3n permanente del museo.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p>GETXO<\/p>\n<p><strong><u>\u00a0<\/u><\/strong><\/p>\n<p><strong>Puente Bizkaia<\/strong><\/p>\n<p>94 480 10 12<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>50% descuento en la actividad \u201cEscala al cielo y ca\u00edda libre desde el Puente Bizkaia\u201d. Precio aplicado descuento: 30\u20ac. Conviene reserva previa realizando inscripci\u00f3n en la web: <a href=\"http:\/\/www.ojoguarenaaventura.com\">www.ojoguarenaaventura.com<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>KARRANTZA<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Museo Antigua F\u00e1brica de Dolomitas<\/strong><\/p>\n<p>94 680 69 28 \/ 696 446 301<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>17:00 Taller graffiti infantil pintando con \u00f3xido de hierro \u201cEllos crean\u201d. Gratuito. Plazas limitadas. Necesaria reserva previa.<\/p>\n<p>&nbsp;<\/p>\n<p>19 de mayo.<\/p>\n<p>12:00 Visita guiada &#8220;A la sombra del desarrollo&#8221;. Gratuita. Plazas limitadas. Necesaria reserva previa.<\/p>\n<p>&nbsp;<\/p>\n<p>KORTEZUBI<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Santimami\u00f1e<\/strong><\/p>\n<p>94 465 16 57<\/p>\n<p>&nbsp;<\/p>\n<p>18 y 19 de mayo.<\/p>\n<p>Entrada gratuita.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>LEIOA<\/p>\n<p><strong>Museo Vasco de Historia de la Medicina <\/strong><\/p>\n<p>94 601 27 90<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>&nbsp;<\/p>\n<p>LOIU<\/p>\n<p><strong>Museo de Historia Natural \u201cAndr\u00e9s de Urdaneta\u201d <\/strong><\/p>\n<p>94 453 33 08<\/p>\n<p>&nbsp;<\/p>\n<p>2 de mayo al 10 de junio, en\u00a0 horario escolar.<\/p>\n<p>XIX Exposici\u00f3n \u201cUn viaje alunizante. 50 aniversario de la llegada a la luna&#8221; (Colaboran: Museo Lunar de Fresnedillas de la Oliva y el INTA). Necesaria reserva previa.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MA\u00d1ARIA<\/p>\n<p><strong>Fundaci\u00f3n Hontza Museoa <\/strong><\/p>\n<p>94 621 65 55<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita.<\/p>\n<p>&nbsp;<\/p>\n<p>12:00 Visita guiada al museo.<\/p>\n<p>13:00 Visita guiada al laboratorio y al almac\u00e9n a cargo del fundador del museo Enrike Huerta.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>19 de mayo.<\/p>\n<p>Entrada gratuita.<\/p>\n<p>&nbsp;<\/p>\n<p>12:00 Visita guiada al museo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>MUSKIZ<\/p>\n<p><strong>Ferrer\u00eda de El Pobal<\/strong><\/p>\n<p>629 271 516<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada gratuita al museo y obsequio.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>OROZKO<\/p>\n<p><strong>Museo de Orozko<\/strong><\/p>\n<p>946 33 98 23<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada y visitas guiadas gratuitas al museo.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>PLENTZIA<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Museo Plasentia de Butr\u00f3n<\/strong><\/p>\n<p>94 677 37 25<\/p>\n<p>&nbsp;<\/p>\n<p>Del 15 al 18 de mayo.<\/p>\n<p>Visita guiada a la exposici\u00f3n temporal &#8220;Naufragios en el Golfo de Bizkaia&#8221;. Gratuita. Necesaria reserva previa.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>PORTUGALETE<\/p>\n<p><strong>RIALIA-Museo de la industria<\/strong><\/p>\n<p>94 472 43 84<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>Entrada y actividades gratuitas.<\/p>\n<p>&nbsp;<\/p>\n<p>12:00 Taller de circo: equilibrio y malabares. Gratuito. Mayores de 5 a\u00f1os.<\/p>\n<p>&nbsp;<\/p>\n<p>19 de mayo.<\/p>\n<p>Entrada y actividades gratuitas.<\/p>\n<p>&nbsp;<\/p>\n<p>12:00 Exhibici\u00f3n de deporte rural a cargo de los harrijasotzailes I\u00f1axio Perurena y Karmele Gisasola y Fausto Mugerza, corte vertical australiano.<\/p>\n<p>&nbsp;<\/p>\n<p>13:00 Visita guiada al museo. Gratuita. Necesaria reserva previa.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>SANTURTZI<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Santurtzi Itsasoa Museoa<\/strong><\/p>\n<p>94 483\u00a0 94 94<\/p>\n<p>&nbsp;<\/p>\n<p>18 y 19 de mayo.<\/p>\n<p>Entrada gratuita.<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>11:30 Taller marinero y subasta de pescado txiki. Gratuito. Se recomienda reserva previa. A partir de 5 a\u00f1os. Euskaraz.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>19 de mayo.<\/p>\n<p>12:00 Subasta de pescado y visita teatralizada. 2\u20ac. Se recomienda reserva previa. Castellano.<\/p>\n<p>&nbsp;<\/p>\n<p>25 de mayo.<\/p>\n<p>18:00 Salida fotogr\u00e1fica \u201cSanturtzi marinero\u201d. 2\u20ac. Se recomienda reserva previa. Castellano.<\/p>\n<p>&nbsp;<\/p>\n<p>26 de mayo.<\/p>\n<p>11:30 Taller marinero: Construyendo el pesquero Agurtza. Gratuito. Se recomienda reserva previa. Euskaraz.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Centro de interpretaci\u00f3n de la t\u00e9cnica de pesca Agurtza<\/strong><\/p>\n<p>94 483\u00a0 94 94<\/p>\n<p>&nbsp;<\/p>\n<p>18, 19, 25 y 26 de mayo.<\/p>\n<p>11:00 y 17:30 Visita guiada. Gratuita. Se recomienda reserva previa.<\/p>\n<p>&nbsp;<\/p>\n<p>18 de mayo.<\/p>\n<p>12:30 Visita teatralizada \u201cPesquero Agurtza\u201d. Gratuita. Se recomienda reserva previa.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>SOPUERTA<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Museo de Las Encartaciones<\/strong><\/p>\n<p>94 650 44 88<\/p>\n<p>&nbsp;<\/p>\n<p>19 de mayo.<\/p>\n<p>10:00-15:00 Itinerario cultural: \u201cEl esplendor de la arquitectura contempor\u00e1nea\u201d. Gratuita. Necesaria reserva previa: <a href=\"mailto:946504488\/946104815\/enkarterrimuseoa@bizkaia.eus\">946504488\/946104815\/enkarterrimuseoa@bizkaia.eus<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>ZIORTZA-BOLIVAR<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Museo Sim\u00f3n-Bolivar<\/strong><\/p>\n<p>94 616 41 14<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>18 de mayo.<\/p>\n<p>Apertura especial de 10:00-14:00.<\/p>\n<p>11:00 Visita guiada al museo. Gratuita. Necesaria reserva previa. Plazas limitadas<\/p>\n<p>12:00 Cuenta-cuentos: \u201dMunduko ipuinak\u201d. Gratuito. Euskaraz<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os informamos de las actividades organizadas en los museos con motivo del D\u00eda Internacional de los museos. &nbsp; Los museos como ejes culturales: el futuro de las tradiciones. \u00a0 BILBAO \u00a0 Arkeologi Museoa 94 404 09 90 18 de mayo. Jornada de puertas abiertas: entrada y actividades gratuitas. &nbsp; 18 de mayo. 11:30 Taller familiar: [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18933,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[131],"tags":[],"class_list":["post-31292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","grve-entry-item","grve-blog-item"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00eda Internacional de los Museos - Puente Colgante<\/title>\n<meta name=\"description\" content=\"Os informamos de las actividades organizadas en los museos con motivo del D\u00eda Internacional de los museos. &nbsp; Los museos como ejes culturales: el\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00eda Internacional de los Museos - Puente Colgante\" \/>\n<meta property=\"og:description\" content=\"Os informamos de las actividades organizadas en los museos con motivo del D\u00eda Internacional de los museos. &nbsp; Los museos como ejes culturales: el\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/\" \/>\n<meta property=\"og:site_name\" content=\"Puente Colgante\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-03T10:44:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/puente-colgante.com\/wp-content\/uploads\/2019\/02\/dia-internacional-museos-18-mayo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"375\" \/>\n\t<meta property=\"og:image:height\" content=\"565\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/\"},\"author\":{\"name\":\"Antonio\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/person\/61a66dd5a3de4d2d599d45bab0a49d21\"},\"headline\":\"D\u00eda Internacional de los Museos\",\"datePublished\":\"2019-05-03T10:44:08+00:00\",\"dateModified\":\"2019-05-03T10:44:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/\"},\"wordCount\":1168,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/puente-colgante.com\/#organization\"},\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/\",\"url\":\"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/\",\"name\":\"D\u00eda Internacional de los Museos - Puente Colgante\",\"isPartOf\":{\"@id\":\"https:\/\/puente-colgante.com\/#website\"},\"datePublished\":\"2019-05-03T10:44:08+00:00\",\"dateModified\":\"2019-05-03T10:44:08+00:00\",\"description\":\"Os informamos de las actividades organizadas en los museos con motivo del D\u00eda Internacional de los museos. &nbsp; Los museos como ejes culturales: el\",\"breadcrumb\":{\"@id\":\"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/puente-colgante.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00eda Internacional de los Museos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/puente-colgante.com\/#website\",\"url\":\"https:\/\/puente-colgante.com\/\",\"name\":\"Puente Colgante\",\"description\":\"Web Oficial del Puente Colgante | Puente Bizkaia\",\"publisher\":{\"@id\":\"https:\/\/puente-colgante.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/puente-colgante.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/puente-colgante.com\/#organization\",\"name\":\"Puente Colgante\",\"url\":\"https:\/\/puente-colgante.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png\",\"contentUrl\":\"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png\",\"width\":742,\"height\":560,\"caption\":\"Puente Colgante\"},\"image\":{\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/person\/61a66dd5a3de4d2d599d45bab0a49d21\",\"name\":\"Antonio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0c578ca6c65e9c58f9826a9d928a3eaf869ee93bc9edc5ca21ec3c77c82b452e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0c578ca6c65e9c58f9826a9d928a3eaf869ee93bc9edc5ca21ec3c77c82b452e?s=96&d=mm&r=g\",\"caption\":\"Antonio\"},\"url\":\"https:\/\/puente-colgante.com\/en\/author\/usr-antonio\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda Internacional de los Museos - Puente Colgante","description":"Os informamos de las actividades organizadas en los museos con motivo del D\u00eda Internacional de los museos. &nbsp; Los museos como ejes culturales: el","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/","og_locale":"en_US","og_type":"article","og_title":"D\u00eda Internacional de los Museos - Puente Colgante","og_description":"Os informamos de las actividades organizadas en los museos con motivo del D\u00eda Internacional de los museos. &nbsp; Los museos como ejes culturales: el","og_url":"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/","og_site_name":"Puente Colgante","article_published_time":"2019-05-03T10:44:08+00:00","og_image":[{"width":375,"height":565,"url":"https:\/\/puente-colgante.com\/wp-content\/uploads\/2019\/02\/dia-internacional-museos-18-mayo.jpg","type":"image\/jpeg"}],"author":"Antonio","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Antonio","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/#article","isPartOf":{"@id":"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/"},"author":{"name":"Antonio","@id":"https:\/\/puente-colgante.com\/#\/schema\/person\/61a66dd5a3de4d2d599d45bab0a49d21"},"headline":"D\u00eda Internacional de los Museos","datePublished":"2019-05-03T10:44:08+00:00","dateModified":"2019-05-03T10:44:08+00:00","mainEntityOfPage":{"@id":"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/"},"wordCount":1168,"commentCount":0,"publisher":{"@id":"https:\/\/puente-colgante.com\/#organization"},"articleSection":["News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/","url":"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/","name":"D\u00eda Internacional de los Museos - Puente Colgante","isPartOf":{"@id":"https:\/\/puente-colgante.com\/#website"},"datePublished":"2019-05-03T10:44:08+00:00","dateModified":"2019-05-03T10:44:08+00:00","description":"Os informamos de las actividades organizadas en los museos con motivo del D\u00eda Internacional de los museos. &nbsp; Los museos como ejes culturales: el","breadcrumb":{"@id":"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/puente-colgante.com\/en\/dia-internacional-de-los-museos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/puente-colgante.com\/en\/"},{"@type":"ListItem","position":2,"name":"D\u00eda Internacional de los Museos"}]},{"@type":"WebSite","@id":"https:\/\/puente-colgante.com\/#website","url":"https:\/\/puente-colgante.com\/","name":"Puente Colgante","description":"Web Oficial del Puente Colgante | Puente Bizkaia","publisher":{"@id":"https:\/\/puente-colgante.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/puente-colgante.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/puente-colgante.com\/#organization","name":"Puente Colgante","url":"https:\/\/puente-colgante.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/","url":"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png","contentUrl":"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png","width":742,"height":560,"caption":"Puente Colgante"},"image":{"@id":"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/puente-colgante.com\/#\/schema\/person\/61a66dd5a3de4d2d599d45bab0a49d21","name":"Antonio","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/puente-colgante.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0c578ca6c65e9c58f9826a9d928a3eaf869ee93bc9edc5ca21ec3c77c82b452e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0c578ca6c65e9c58f9826a9d928a3eaf869ee93bc9edc5ca21ec3c77c82b452e?s=96&d=mm&r=g","caption":"Antonio"},"url":"https:\/\/puente-colgante.com\/en\/author\/usr-antonio\/"}]}},"_links":{"self":[{"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/posts\/31292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/comments?post=31292"}],"version-history":[{"count":0,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/posts\/31292\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/media\/18933"}],"wp:attachment":[{"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/media?parent=31292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/categories?post=31292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/tags?post=31292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}