{"id":31144,"date":"2019-01-11T08:21:10","date_gmt":"2019-01-11T07:21:10","guid":{"rendered":"https:\/\/puente-colgante.com\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/"},"modified":"2019-01-11T08:21:10","modified_gmt":"2019-01-11T07:21:10","slug":"jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible","status":"publish","type":"post","link":"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/","title":{"rendered":"Jornada UOC &#8211; UNESCO Etxea \u201cIncorporar la agenda 2030 en la estrategia de tu empresa. Claves para el desarrollo sostenible\u201d"},"content":{"rendered":"<p>Con el lema &#8220;Transformar nuestro mundo&#8221;, en 2015, los l\u00edderes mundiales aprobaron la Agenda 2030 de las Naciones Unidas para el Desarrollo Sostenible y se comprometieron a lograr los diecisiete objetivos que la conforman para cambiar nuestro mundo en los pr\u00f3ximos quince a\u00f1os. La Agenda, consensuada en un proceso participativo donde gobiernos y sociedad civil estuvieron involucrados, tiene un alcance que va m\u00e1s all\u00e1 de la agenda social y debe abordarse de forma transversal. Adem\u00e1s, es una agenda que interpela a todos los pa\u00edses del mundo, desarrollados y en v\u00edas de desarrollo, para conseguir la transformaci\u00f3n.<\/p>\n<p>\u00bfC\u00f3mo podemos contribuir a erradicar el hambre? \u00bfQu\u00e9 relaci\u00f3n tienen la paz, la justicia y las instituciones s\u00f3lidas? \u00bfNos afecta el cambio clim\u00e1tico? \u00bfQu\u00e9 papel pueden y deben jugar las empresas en estos 17 objetivos?<\/p>\n<p>La sostenibilidad empresarial comienza con el sistema de valores de una empresa y un enfoque basado en principios para hacer negocios. Esto significa que opera de manera que, como m\u00ednimo, debe cumplir con las responsabilidades fundamentales en las \u00e1reas de derechos humanos, trabajo, medio ambiente y anticorrupci\u00f3n. Las empresas responsables promulgan los mismos valores y principios, y saben que las buenas pr\u00e1cticas en un \u00e1rea no compensan el da\u00f1o en otro. Mediante la incorporaci\u00f3n de los diez principios del Pacto Mundial de la ONU en estrategias, pol\u00edticas y procedimientos, y el establecimiento de una cultura de integridad, las empresas no s\u00f3lo est\u00e1n defendiendo sus responsabilidades b\u00e1sicas de las personas y el planeta, sino tambi\u00e9n preparando el escenario para el \u00e9xito a largo plazo.<\/p>\n<p>Unesco Etxea y la UOC proponen una jornada dirigida al mundo empresarial y de las organizaciones, para dar a conocer la Agenda 2030 de las Naciones Unidas para el Desarrollo Sostenible, generar debate sobre la responsabilidad que las empresas tienen para ayudar a conseguir los 17 objetivos mencionados, dar a conocer experiencias de \u00e9xito en este \u00e1mbito y promover un movimiento global para que las empresas se comprometan con la sostenibilidad del planeta.<\/p>\n<p>&nbsp;<\/p>\n<p>En URL: [<a href=\"http:\/\/symposium.uoc.edu\/29135\/detail\/jornada-uoc-unesco-etxea-lincorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa.-claves-para-el-.html\" target=\"_blank\" rel=\"noopener\">http:\/\/symposium.uoc.edu\/29135\/detail\/jornada-uoc-unesco-etxea-lincorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa.-claves-para-el-.html<\/a>]<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el lema &#8220;Transformar nuestro mundo&#8221;, en 2015, los l\u00edderes mundiales aprobaron la Agenda 2030 de las Naciones Unidas para el Desarrollo Sostenible y se comprometieron a lograr los diecisiete objetivos que la conforman para cambiar nuestro mundo en los pr\u00f3ximos quince a\u00f1os. La Agenda, consensuada en un proceso participativo donde gobiernos y sociedad civil [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[131],"tags":[],"class_list":["post-31144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","grve-entry-item","grve-blog-item"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jornada UOC - UNESCO Etxea \u201cIncorporar la agenda 2030 en la estrategia de tu empresa. Claves para el desarrollo sostenible\u201d - Puente Colgante<\/title>\n<meta name=\"description\" content=\"Con el lema &quot;Transformar nuestro mundo&quot;, en 2015, los l\u00edderes mundiales aprobaron la Agenda 2030 de las Naciones Unidas para el Desarrollo Sostenible y se\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jornada UOC - UNESCO Etxea \u201cIncorporar la agenda 2030 en la estrategia de tu empresa. Claves para el desarrollo sostenible\u201d - Puente Colgante\" \/>\n<meta property=\"og:description\" content=\"Con el lema &quot;Transformar nuestro mundo&quot;, en 2015, los l\u00edderes mundiales aprobaron la Agenda 2030 de las Naciones Unidas para el Desarrollo Sostenible y se\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/\" \/>\n<meta property=\"og:site_name\" content=\"Puente Colgante\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-11T07:21:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/puente-colgante.com\/wp-content\/uploads\/2019\/01\/fotonoticia_20150925141553_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/person\/1cb7a33dae376b9d2c073110e8ec4b9b\"},\"headline\":\"Jornada UOC &#8211; UNESCO Etxea \u201cIncorporar la agenda 2030 en la estrategia de tu empresa. Claves para el desarrollo sostenible\u201d\",\"datePublished\":\"2019-01-11T07:21:10+00:00\",\"dateModified\":\"2019-01-11T07:21:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/\"},\"wordCount\":376,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/puente-colgante.com\/#organization\"},\"articleSection\":[\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/\",\"url\":\"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/\",\"name\":\"Jornada UOC - UNESCO Etxea \u201cIncorporar la agenda 2030 en la estrategia de tu empresa. Claves para el desarrollo sostenible\u201d - Puente Colgante\",\"isPartOf\":{\"@id\":\"https:\/\/puente-colgante.com\/#website\"},\"datePublished\":\"2019-01-11T07:21:10+00:00\",\"dateModified\":\"2019-01-11T07:21:10+00:00\",\"description\":\"Con el lema \\\"Transformar nuestro mundo\\\", en 2015, los l\u00edderes mundiales aprobaron la Agenda 2030 de las Naciones Unidas para el Desarrollo Sostenible y se\",\"breadcrumb\":{\"@id\":\"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/puente-colgante.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jornada UOC &#8211; UNESCO Etxea \u201cIncorporar la agenda 2030 en la estrategia de tu empresa. Claves para el desarrollo sostenible\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/puente-colgante.com\/#website\",\"url\":\"https:\/\/puente-colgante.com\/\",\"name\":\"Puente Colgante\",\"description\":\"Web Oficial del Puente Colgante | Puente Bizkaia\",\"publisher\":{\"@id\":\"https:\/\/puente-colgante.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/puente-colgante.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/puente-colgante.com\/#organization\",\"name\":\"Puente Colgante\",\"url\":\"https:\/\/puente-colgante.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png\",\"contentUrl\":\"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png\",\"width\":742,\"height\":560,\"caption\":\"Puente Colgante\"},\"image\":{\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/person\/1cb7a33dae376b9d2c073110e8ec4b9b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fd07c919907115af214a1e73130252784e8d50e757c8cd800e69acdfe5f2ff28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fd07c919907115af214a1e73130252784e8d50e757c8cd800e69acdfe5f2ff28?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/puente-colgante.com\"],\"url\":\"https:\/\/puente-colgante.com\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jornada UOC - UNESCO Etxea \u201cIncorporar la agenda 2030 en la estrategia de tu empresa. Claves para el desarrollo sostenible\u201d - Puente Colgante","description":"Con el lema \"Transformar nuestro mundo\", en 2015, los l\u00edderes mundiales aprobaron la Agenda 2030 de las Naciones Unidas para el Desarrollo Sostenible y se","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/","og_locale":"en_US","og_type":"article","og_title":"Jornada UOC - UNESCO Etxea \u201cIncorporar la agenda 2030 en la estrategia de tu empresa. Claves para el desarrollo sostenible\u201d - Puente Colgante","og_description":"Con el lema \"Transformar nuestro mundo\", en 2015, los l\u00edderes mundiales aprobaron la Agenda 2030 de las Naciones Unidas para el Desarrollo Sostenible y se","og_url":"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/","og_site_name":"Puente Colgante","article_published_time":"2019-01-11T07:21:10+00:00","og_image":[{"width":1280,"height":854,"url":"https:\/\/puente-colgante.com\/wp-content\/uploads\/2019\/01\/fotonoticia_20150925141553_1280.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/#article","isPartOf":{"@id":"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/"},"author":{"name":"admin","@id":"https:\/\/puente-colgante.com\/#\/schema\/person\/1cb7a33dae376b9d2c073110e8ec4b9b"},"headline":"Jornada UOC &#8211; UNESCO Etxea \u201cIncorporar la agenda 2030 en la estrategia de tu empresa. Claves para el desarrollo sostenible\u201d","datePublished":"2019-01-11T07:21:10+00:00","dateModified":"2019-01-11T07:21:10+00:00","mainEntityOfPage":{"@id":"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/"},"wordCount":376,"commentCount":0,"publisher":{"@id":"https:\/\/puente-colgante.com\/#organization"},"articleSection":["News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/","url":"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/","name":"Jornada UOC - UNESCO Etxea \u201cIncorporar la agenda 2030 en la estrategia de tu empresa. Claves para el desarrollo sostenible\u201d - Puente Colgante","isPartOf":{"@id":"https:\/\/puente-colgante.com\/#website"},"datePublished":"2019-01-11T07:21:10+00:00","dateModified":"2019-01-11T07:21:10+00:00","description":"Con el lema \"Transformar nuestro mundo\", en 2015, los l\u00edderes mundiales aprobaron la Agenda 2030 de las Naciones Unidas para el Desarrollo Sostenible y se","breadcrumb":{"@id":"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/puente-colgante.com\/en\/jornada-uoc-unesco-etxea-incorporar-la-agenda-2030-en-la-estrategia-de-tu-empresa-claves-para-el-desarrollo-sostenible\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/puente-colgante.com\/en\/"},{"@type":"ListItem","position":2,"name":"Jornada UOC &#8211; UNESCO Etxea \u201cIncorporar la agenda 2030 en la estrategia de tu empresa. Claves para el desarrollo sostenible\u201d"}]},{"@type":"WebSite","@id":"https:\/\/puente-colgante.com\/#website","url":"https:\/\/puente-colgante.com\/","name":"Puente Colgante","description":"Web Oficial del Puente Colgante | Puente Bizkaia","publisher":{"@id":"https:\/\/puente-colgante.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/puente-colgante.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/puente-colgante.com\/#organization","name":"Puente Colgante","url":"https:\/\/puente-colgante.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/","url":"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png","contentUrl":"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png","width":742,"height":560,"caption":"Puente Colgante"},"image":{"@id":"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/puente-colgante.com\/#\/schema\/person\/1cb7a33dae376b9d2c073110e8ec4b9b","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/puente-colgante.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fd07c919907115af214a1e73130252784e8d50e757c8cd800e69acdfe5f2ff28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fd07c919907115af214a1e73130252784e8d50e757c8cd800e69acdfe5f2ff28?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/puente-colgante.com"],"url":"https:\/\/puente-colgante.com\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/posts\/31144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/comments?post=31144"}],"version-history":[{"count":0,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/posts\/31144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/media\/18829"}],"wp:attachment":[{"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/media?parent=31144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/categories?post=31144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/tags?post=31144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}