{"id":30737,"date":"2018-08-07T05:00:21","date_gmt":"2018-08-07T03:00:21","guid":{"rendered":"https:\/\/puente-colgante.com\/pintxo-pote-por-la-ria-2\/"},"modified":"2018-08-07T05:00:21","modified_gmt":"2018-08-07T03:00:21","slug":"pintxo-pote-por-la-ria-2","status":"publish","type":"post","link":"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/","title":{"rendered":"PINTXO POTE POR LA R\u00cdA"},"content":{"rendered":"<p>Te proponemos embarcarte en una aventura gastron\u00f3mica por la r\u00eda de Bilbao. Pas\u00e9ate en velero mientras degustas un sabroso pintxo-pote.<\/p>\n<p>Descubre la historia de la villa de una forma singular y observa el carism\u00e1tico Puente Bizkaia o el renovado campo de San Mam\u00e9s desde otra perspectiva.<\/p>\n<p>S\u00famate a esta aventura y zarpa entre las dos m\u00e1rgenes de la r\u00eda. Ap\u00fantate en:<\/p>\n<p><a href=\"http:\/\/www.getxo.eus\/es\/turismo\/que-hacer\/velero-pintxopote\">http:\/\/www.getxo.eus\/es\/turismo\/que-hacer\/velero-pintxopote<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Te proponemos embarcarte en una aventura gastron\u00f3mica por la r\u00eda de Bilbao. Pas\u00e9ate en velero mientras degustas un sabroso pintxo-pote. Descubre la historia de la villa de una forma singular y observa el carism\u00e1tico Puente Bizkaia o el renovado campo de San Mam\u00e9s desde otra perspectiva. S\u00famate a esta aventura y zarpa entre las dos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18258,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[157,131],"tags":[],"class_list":["post-30737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-125th-aniversary","category-news","grve-entry-item","grve-blog-item"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PINTXO POTE POR LA R\u00cdA - Puente Colgante<\/title>\n<meta name=\"description\" content=\"Te proponemos embarcarte en una aventura gastron\u00f3mica por la r\u00eda de Bilbao. Pas\u00e9ate en velero mientras degustas un sabroso pintxo-pote. Descubre la\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PINTXO POTE POR LA R\u00cdA - Puente Colgante\" \/>\n<meta property=\"og:description\" content=\"Te proponemos embarcarte en una aventura gastron\u00f3mica por la r\u00eda de Bilbao. Pas\u00e9ate en velero mientras degustas un sabroso pintxo-pote. Descubre la\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Puente Colgante\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-07T03:00:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/puente-colgante.com\/wp-content\/uploads\/2018\/08\/Plan_8_Pintxo_pote.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1120\" \/>\n\t<meta property=\"og:image:height\" content=\"448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/person\/1cb7a33dae376b9d2c073110e8ec4b9b\"},\"headline\":\"PINTXO POTE POR LA R\u00cdA\",\"datePublished\":\"2018-08-07T03:00:21+00:00\",\"dateModified\":\"2018-08-07T03:00:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/\"},\"wordCount\":84,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/puente-colgante.com\/#organization\"},\"articleSection\":[\"125th aniversary\",\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/\",\"url\":\"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/\",\"name\":\"PINTXO POTE POR LA R\u00cdA - Puente Colgante\",\"isPartOf\":{\"@id\":\"https:\/\/puente-colgante.com\/#website\"},\"datePublished\":\"2018-08-07T03:00:21+00:00\",\"dateModified\":\"2018-08-07T03:00:21+00:00\",\"description\":\"Te proponemos embarcarte en una aventura gastron\u00f3mica por la r\u00eda de Bilbao. Pas\u00e9ate en velero mientras degustas un sabroso pintxo-pote. Descubre la\",\"breadcrumb\":{\"@id\":\"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/puente-colgante.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PINTXO POTE POR LA R\u00cdA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/puente-colgante.com\/#website\",\"url\":\"https:\/\/puente-colgante.com\/\",\"name\":\"Puente Colgante\",\"description\":\"Web Oficial del Puente Colgante | Puente Bizkaia\",\"publisher\":{\"@id\":\"https:\/\/puente-colgante.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/puente-colgante.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/puente-colgante.com\/#organization\",\"name\":\"Puente Colgante\",\"url\":\"https:\/\/puente-colgante.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png\",\"contentUrl\":\"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png\",\"width\":742,\"height\":560,\"caption\":\"Puente Colgante\"},\"image\":{\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/person\/1cb7a33dae376b9d2c073110e8ec4b9b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fd07c919907115af214a1e73130252784e8d50e757c8cd800e69acdfe5f2ff28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fd07c919907115af214a1e73130252784e8d50e757c8cd800e69acdfe5f2ff28?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/puente-colgante.com\"],\"url\":\"https:\/\/puente-colgante.com\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PINTXO POTE POR LA R\u00cdA - Puente Colgante","description":"Te proponemos embarcarte en una aventura gastron\u00f3mica por la r\u00eda de Bilbao. Pas\u00e9ate en velero mientras degustas un sabroso pintxo-pote. Descubre la","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/","og_locale":"en_US","og_type":"article","og_title":"PINTXO POTE POR LA R\u00cdA - Puente Colgante","og_description":"Te proponemos embarcarte en una aventura gastron\u00f3mica por la r\u00eda de Bilbao. Pas\u00e9ate en velero mientras degustas un sabroso pintxo-pote. Descubre la","og_url":"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/","og_site_name":"Puente Colgante","article_published_time":"2018-08-07T03:00:21+00:00","og_image":[{"width":1120,"height":448,"url":"https:\/\/puente-colgante.com\/wp-content\/uploads\/2018\/08\/Plan_8_Pintxo_pote.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/#article","isPartOf":{"@id":"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/"},"author":{"name":"admin","@id":"https:\/\/puente-colgante.com\/#\/schema\/person\/1cb7a33dae376b9d2c073110e8ec4b9b"},"headline":"PINTXO POTE POR LA R\u00cdA","datePublished":"2018-08-07T03:00:21+00:00","dateModified":"2018-08-07T03:00:21+00:00","mainEntityOfPage":{"@id":"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/"},"wordCount":84,"commentCount":0,"publisher":{"@id":"https:\/\/puente-colgante.com\/#organization"},"articleSection":["125th aniversary","News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/","url":"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/","name":"PINTXO POTE POR LA R\u00cdA - Puente Colgante","isPartOf":{"@id":"https:\/\/puente-colgante.com\/#website"},"datePublished":"2018-08-07T03:00:21+00:00","dateModified":"2018-08-07T03:00:21+00:00","description":"Te proponemos embarcarte en una aventura gastron\u00f3mica por la r\u00eda de Bilbao. Pas\u00e9ate en velero mientras degustas un sabroso pintxo-pote. Descubre la","breadcrumb":{"@id":"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/puente-colgante.com\/en\/pintxo-pote-por-la-ria-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/puente-colgante.com\/en\/"},{"@type":"ListItem","position":2,"name":"PINTXO POTE POR LA R\u00cdA"}]},{"@type":"WebSite","@id":"https:\/\/puente-colgante.com\/#website","url":"https:\/\/puente-colgante.com\/","name":"Puente Colgante","description":"Web Oficial del Puente Colgante | Puente Bizkaia","publisher":{"@id":"https:\/\/puente-colgante.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/puente-colgante.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/puente-colgante.com\/#organization","name":"Puente Colgante","url":"https:\/\/puente-colgante.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/","url":"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png","contentUrl":"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png","width":742,"height":560,"caption":"Puente Colgante"},"image":{"@id":"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/puente-colgante.com\/#\/schema\/person\/1cb7a33dae376b9d2c073110e8ec4b9b","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/puente-colgante.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fd07c919907115af214a1e73130252784e8d50e757c8cd800e69acdfe5f2ff28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fd07c919907115af214a1e73130252784e8d50e757c8cd800e69acdfe5f2ff28?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/puente-colgante.com"],"url":"https:\/\/puente-colgante.com\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/posts\/30737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/comments?post=30737"}],"version-history":[{"count":0,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/posts\/30737\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/media\/18258"}],"wp:attachment":[{"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/media?parent=30737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/categories?post=30737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/tags?post=30737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}