{"id":16997,"date":"2018-02-23T10:37:58","date_gmt":"2018-02-23T10:37:58","guid":{"rendered":"https:\/\/puente-colgante.com\/?p=16997\/"},"modified":"2018-02-23T10:37:58","modified_gmt":"2018-02-23T10:37:58","slug":"puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2","status":"publish","type":"post","link":"https:\/\/puente-colgante.com\/en\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/","title":{"rendered":"El Puente Bizkaia ya cuenta con el Certificado de Zona Cardioprotegida NIVEL 2"},"content":{"rendered":"<p>El Puente de Bizkaia ya es Zona Cardioprotegida Nivel 2<\/p>\n<p>Habiendo ya realizado las siguientes actuaciones:<\/p>\n<ul>\n<li>Formaci\u00f3n de su personal en t\u00e9cnicas de reanimaci\u00f3n cardiopulmonar (R.C.P.)<\/li>\n<li>Disponibilidad de equipos desfibriladores en sus instalaciones.<\/li>\n<li>Difusi\u00f3n de dicho Plan en su entorno de actividad.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>El Puente de Bizkaia ya es Zona Cardioprotegida Nivel 2 Habiendo ya realizado las siguientes actuaciones: Formaci\u00f3n de su personal en t\u00e9cnicas de reanimaci\u00f3n cardiopulmonar (R.C.P.) Disponibilidad de equipos desfibriladores en sus instalaciones. Difusi\u00f3n de dicho Plan en su entorno de actividad.<\/p>\n","protected":false},"author":1,"featured_media":17002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[125],"tags":[],"class_list":["post-16997","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","grve-entry-item","grve-blog-item"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Puente Bizkaia ya cuenta con el Certificado de Zona Cardioprotegida NIVEL 2 - Puente Colgante<\/title>\n<meta name=\"description\" content=\"El Puente de Bizkaia ya es Zona Cardioprotegida Nivel 2 tras haber realizado las actuaciones oportunas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Puente Bizkaia ya cuenta con el Certificado de Zona Cardioprotegida NIVEL 2 - Puente Colgante\" \/>\n<meta property=\"og:description\" content=\"El Puente de Bizkaia ya es Zona Cardioprotegida Nivel 2 tras haber realizado las actuaciones oportunas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Puente Colgante\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-23T10:37:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/puente-colgante.com\/wp-content\/uploads\/2018\/02\/puente-bizkaia-zona-cardioprotegida-nivel-2-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/person\/1cb7a33dae376b9d2c073110e8ec4b9b\"},\"headline\":\"El Puente Bizkaia ya cuenta con el Certificado de Zona Cardioprotegida NIVEL 2\",\"datePublished\":\"2018-02-23T10:37:58+00:00\",\"dateModified\":\"2018-02-23T10:37:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/\"},\"wordCount\":59,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/puente-colgante.com\/#organization\"},\"articleSection\":[\"Noticias\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/\",\"url\":\"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/\",\"name\":\"El Puente Bizkaia ya cuenta con el Certificado de Zona Cardioprotegida NIVEL 2 - Puente Colgante\",\"isPartOf\":{\"@id\":\"https:\/\/puente-colgante.com\/#website\"},\"datePublished\":\"2018-02-23T10:37:58+00:00\",\"dateModified\":\"2018-02-23T10:37:58+00:00\",\"description\":\"El Puente de Bizkaia ya es Zona Cardioprotegida Nivel 2 tras haber realizado las actuaciones oportunas\",\"breadcrumb\":{\"@id\":\"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/puente-colgante.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Puente Bizkaia ya cuenta con el Certificado de Zona Cardioprotegida NIVEL 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/puente-colgante.com\/#website\",\"url\":\"https:\/\/puente-colgante.com\/\",\"name\":\"Puente Colgante\",\"description\":\"Web Oficial del Puente Colgante | Puente Bizkaia\",\"publisher\":{\"@id\":\"https:\/\/puente-colgante.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/puente-colgante.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/puente-colgante.com\/#organization\",\"name\":\"Puente Colgante\",\"url\":\"https:\/\/puente-colgante.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png\",\"contentUrl\":\"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png\",\"width\":742,\"height\":560,\"caption\":\"Puente Colgante\"},\"image\":{\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/person\/1cb7a33dae376b9d2c073110e8ec4b9b\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/puente-colgante.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fd07c919907115af214a1e73130252784e8d50e757c8cd800e69acdfe5f2ff28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fd07c919907115af214a1e73130252784e8d50e757c8cd800e69acdfe5f2ff28?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/puente-colgante.com\"],\"url\":\"https:\/\/puente-colgante.com\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Puente Bizkaia ya cuenta con el Certificado de Zona Cardioprotegida NIVEL 2 - Puente Colgante","description":"El Puente de Bizkaia ya es Zona Cardioprotegida Nivel 2 tras haber realizado las actuaciones oportunas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/","og_locale":"en_US","og_type":"article","og_title":"El Puente Bizkaia ya cuenta con el Certificado de Zona Cardioprotegida NIVEL 2 - Puente Colgante","og_description":"El Puente de Bizkaia ya es Zona Cardioprotegida Nivel 2 tras haber realizado las actuaciones oportunas","og_url":"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/","og_site_name":"Puente Colgante","article_published_time":"2018-02-23T10:37:58+00:00","og_image":[{"width":1000,"height":854,"url":"https:\/\/puente-colgante.com\/wp-content\/uploads\/2018\/02\/puente-bizkaia-zona-cardioprotegida-nivel-2-2.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/#article","isPartOf":{"@id":"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/"},"author":{"name":"admin","@id":"https:\/\/puente-colgante.com\/#\/schema\/person\/1cb7a33dae376b9d2c073110e8ec4b9b"},"headline":"El Puente Bizkaia ya cuenta con el Certificado de Zona Cardioprotegida NIVEL 2","datePublished":"2018-02-23T10:37:58+00:00","dateModified":"2018-02-23T10:37:58+00:00","mainEntityOfPage":{"@id":"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/"},"wordCount":59,"commentCount":0,"publisher":{"@id":"https:\/\/puente-colgante.com\/#organization"},"articleSection":["Noticias"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/","url":"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/","name":"El Puente Bizkaia ya cuenta con el Certificado de Zona Cardioprotegida NIVEL 2 - Puente Colgante","isPartOf":{"@id":"https:\/\/puente-colgante.com\/#website"},"datePublished":"2018-02-23T10:37:58+00:00","dateModified":"2018-02-23T10:37:58+00:00","description":"El Puente de Bizkaia ya es Zona Cardioprotegida Nivel 2 tras haber realizado las actuaciones oportunas","breadcrumb":{"@id":"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/puente-colgante.com\/puente-bizkaia-ya-cuenta-certificado-zona-cardioprotegida-nivel-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/puente-colgante.com\/en\/"},{"@type":"ListItem","position":2,"name":"El Puente Bizkaia ya cuenta con el Certificado de Zona Cardioprotegida NIVEL 2"}]},{"@type":"WebSite","@id":"https:\/\/puente-colgante.com\/#website","url":"https:\/\/puente-colgante.com\/","name":"Puente Colgante","description":"Web Oficial del Puente Colgante | Puente Bizkaia","publisher":{"@id":"https:\/\/puente-colgante.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/puente-colgante.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/puente-colgante.com\/#organization","name":"Puente Colgante","url":"https:\/\/puente-colgante.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/","url":"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png","contentUrl":"https:\/\/puente-colgante.com\/wp-content\/uploads\/2024\/02\/Formato-logo.png","width":742,"height":560,"caption":"Puente Colgante"},"image":{"@id":"https:\/\/puente-colgante.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/puente-colgante.com\/#\/schema\/person\/1cb7a33dae376b9d2c073110e8ec4b9b","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/puente-colgante.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fd07c919907115af214a1e73130252784e8d50e757c8cd800e69acdfe5f2ff28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fd07c919907115af214a1e73130252784e8d50e757c8cd800e69acdfe5f2ff28?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/puente-colgante.com"],"url":"https:\/\/puente-colgante.com\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/posts\/16997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/comments?post=16997"}],"version-history":[{"count":0,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/posts\/16997\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/media\/17002"}],"wp:attachment":[{"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/media?parent=16997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/categories?post=16997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/puente-colgante.com\/en\/wp-json\/wp\/v2\/tags?post=16997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}